{"id":88,"date":"2023-06-17T08:34:41","date_gmt":"2023-06-17T11:34:41","guid":{"rendered":"http:\/\/www.ligavpg.com\/blog\/?page_id=88"},"modified":"2025-10-14T21:35:14","modified_gmt":"2025-10-15T00:35:14","slug":"regras","status":"publish","type":"page","link":"https:\/\/ligavpg.com\/blog\/regras\/","title":{"rendered":"Regulamento"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h4 style=\"text-align: center;\"><span style=\"text-align: left; font-size: 18px; font-family: 'trebuchet ms', geneva;\"><strong>REGULAMENTO DE COMPETI\u00c7\u00d5ES<\/strong><\/span><\/h4>\n<p style=\"color: #c6b5bf; text-align: center;\"><span style=\"font-family: 'trebuchet ms', geneva;\"><strong>Regras, Penaliza\u00e7\u00f5es e Recursos<\/strong><\/span><\/p>\n<div style=\"text-align: left; color: #c6b5bf;\">\n<p style=\"text-align: right;\"><span style=\"color: #ff6600;\"><span style=\"color: #339966;\">Data da atualiza\u00e7\u00e3o: 20\/01\/2025<\/span><br \/>\n<\/span><\/p>\n<div style=\"color: #c6b5bf;\" align=\"center\"><span style=\"color: #000000;\">\u00a0<\/span><\/div>\n<h4 style=\"text-align: center;\"><strong><u>REGULAMENTO GERAL DA LIGA VPG<br \/>\nREGRAS DE CONDUTA<\/u><\/strong><\/h4>\n<p>Este regulamento visa padronizar os procedimentos e condutas de todos antes de entrar no servidor e durante todas as sess\u00f5es das corridas. Com ele, voc\u00ea saber\u00e1 antecipadamente qual a conduta correta que voc\u00ea dever\u00e1 adotar em cada situa\u00e7\u00e3o de uma corrida. Al\u00e9m disso, tamb\u00e9m entender\u00e1 as regras b\u00e1sicas e padr\u00f5es para todas as competi\u00e7\u00f5es realizadas.<br \/>\nEstas regras visam impor limites a cada participante para seu pr\u00f3prio benef\u00edcio, pois est\u00e1 em jogo o seu divertimento.<\/p>\n<p>A Liga VPG se v\u00ea na obriga\u00e7\u00e3o de coibir poss\u00edveis abusos que venham a ser cometidos nas competi\u00e7\u00f5es. De forma alguma ser\u00e3o toleradas atitudes de qualquer esp\u00e9cie de agressividade para com os demais participantes e nestes casos a Liga VPG tem total autonomia para a qualquer momento expulsar, se necess\u00e1rio for, qualquer participante das corridas por n\u00f3s organizadas. O respeito entre os participantes \u00e9 a regra b\u00e1sica e se todos a seguirem, tiraremos proveito, garantindo assim o divertimento de todos.<\/p>\n<p>Todo piloto, ao confirmar a sua participa\u00e7\u00e3o, estar\u00e1 de acordo com as regras a seguir, ficando obrigado a cumpri-las. Caso seja necess\u00e1rio, avaliaremos as poss\u00edveis penaliza\u00e7\u00f5es com crit\u00e9rios objetivos e levando-se em considera\u00e7\u00e3o diversos fatores.<\/p>\n<p>Leia e siga corretamente este regulamento. Desta forma, voc\u00ea estar\u00e1 colaborando para o divertimento de todos e principalmente o seu. Todo piloto deve ter em mente que ele \u00e9 o \u00fanico respons\u00e1vel pelos seus atos praticados nos servidores, estando em corridas ou apenas em treinos.<\/p>\n<h4 style=\"text-align: center;\">FUN\u00c7\u00d5ES da Liga VPG:<\/h4>\n<ol>\n<li>A Liga VPG visa trazer divers\u00e3o e entretenimento a todos os participantes.<\/li>\n<li>Todos os competidores concordam com os termos da Liga VPG quanto a seus conceitos de organiza\u00e7\u00e3o.<\/li>\n<li>Todos os participantes, devem sempre manter a esportividade e educa\u00e7\u00e3o durante o transcorrer das atividades.<\/li>\n<li>Qualquer indiv\u00edduo poder\u00e1 participar das atividades da Liga VPG mediante registro no formul\u00e1rio de inscri\u00e7\u00e3o para validar a respectiva corrida ou campeonato.<\/li>\n<li>A organiza\u00e7\u00e3o da Liga VPG reserva-se ao direito de, a qualquer momento, modificar qualquer ponto deste regulamento de forma a assegurar a divers\u00e3o dos participantes.<\/li>\n<\/ol>\n<h4 style=\"text-align: center;\">DO PARTICIPANTE:<\/h4>\n<p>Ao cadastrar-se para os eventos da Liga VPG, o participante:<\/p>\n<ol>\n<li>\u00c9 obrigado a respeitar todas as pessoas envolvidas nos eventos.<\/li>\n<li>N\u00e3o poder\u00e1 insultar algu\u00e9m com algum tipo de ofensa nem discrimina\u00e7\u00e3o.<\/li>\n<li>\u00c9 obrigado a atuar como uma pessoa respons\u00e1vel e adulta tendo atitudes de jogo limpo em todas as sess\u00f5es, oficiais ou n\u00e3o.<\/li>\n<li>N\u00e3o poder\u00e1 dar erros de Desacordos de Arquivos (Mismatchs), nem ter Altas Lat\u00eancias na Transfer\u00eancia de Dados (Lags acima de 300 ms).<\/li>\n<li>\u00c9 de inteira responsabilidade do participante, assegurar que todas as instala\u00e7\u00f5es estejam corretas.<\/li>\n<li>Os pilotos se identificar\u00e3o no Servidor apenas pelo; Nome ou Nome e Sobrenome, n\u00e3o sendo permitido usar nickname ou nome em &#8221; CAIXA ALTA&#8221;, podendo este ser expulso do servidor.<\/li>\n<li>A primeira curva \u00e9 onde h\u00e1 o maior volume de carros pr\u00f3ximos, disputando freadas para ganhar posi\u00e7\u00f5es. Aqui \u00e9 important\u00edssimo que os pilotos respeitem a freada do advers\u00e1rio. Somente tente uma ultrapassagem caso tenha certeza que sua tentativa n\u00e3o ir\u00e1 resultar em um acidente, causando o fim da prova para voc\u00ea e outros pilotos. Voc\u00ea ter\u00e1 mais voltas para tentar a ultrapassagem, lembre-se que na primeira volta os pneus e os freios ainda n\u00e3o estar\u00e3o aquecidos, o que diminui a efic\u00e1cia da frenagem e a ader\u00eancia dos pneus.<br \/>\nToda corrida realizada tem sua dura\u00e7\u00e3o longa e qualquer tentativa precipitada no in\u00edcio da prova pode comprometer seu resultado, portanto procure sempre ter paci\u00eancia, pois ter\u00e1 muitas voltas pela frente. Al\u00e9m disso, \u00e9 um momento tenso onde os erros e os toques podem acontecer e voc\u00ea precisa estar preparado para se livrar deles.<\/li>\n<li>Ser ultrapassado gera uma forte adrenalina nos pilotos envolvidos, pois voc\u00ea n\u00e3o pretende vender a sua posi\u00e7\u00e3o facilmente. Mas defender a sua posi\u00e7\u00e3o imp\u00f5e alguns limites:<br \/>\nA cada vez que um piloto tenta ultrapass\u00e1-lo, voc\u00ea somente poder\u00e1 mudar a sua linha de dire\u00e7\u00e3o (tra\u00e7ado) uma vez, somente ap\u00f3s contornar a curva voc\u00ea poder\u00e1 voltar a linha normal. Esta conduta viabiliza que o piloto possa defender a sua posi\u00e7\u00e3o sem, entretanto, causar perigo ao piloto que est\u00e1 para ultrapass\u00e1-lo e para si pr\u00f3prio.<br \/>\nSe voc\u00ea e outro piloto contornarem uma curva lado a lado, \u00e9 proibido, sob qualquer hip\u00f3tese, deixar seu carro espalhar, para que o piloto que est\u00e1 do lado externo da curva fique sem pista, esta conduta \u00e9 inaceit\u00e1vel. Saiba perder a posi\u00e7\u00e3o, caso n\u00e3o consiga conserv\u00e1-la no momento, e mantenha a concentra\u00e7\u00e3o para retom\u00e1-la mais \u00e0 frente.<br \/>\nSendo ultrapassado em uma curva, jamais mude sua trajet\u00f3ria, para dificultar a manobra do advers\u00e1rio, pois ser\u00e1 considerada infra\u00e7\u00e3o e sujeita as penalidades.<\/li>\n<li>Em caso de pistas estreitas, n\u00e3o \u00e9 permitido ficar com o carro no meio da pista para evitar ser ultrapassado, pois dessa forma n\u00e3o estar\u00e1 deixando o espa\u00e7o devido para o oponente.<\/li>\n<li>N\u00e3o \u00e9 permitido mudar de posi\u00e7\u00e3o na pista na hora da freada para a curva, ap\u00f3s escolher o lado da pista para a defesa, voc\u00ea dever\u00e1 manter a sua linha.<\/li>\n<li>Aconselhamos a utiliza\u00e7\u00e3o do espelho virtual para uma melhor visualiza\u00e7\u00e3o do que ocorre atr\u00e1s de voc\u00ea na pista.<\/li>\n<li>Antes de fazer uma ultrapassagem, estude os pontos seguros para tal. Fa\u00e7a uma an\u00e1lise e descubra em quais curvas voc\u00ea tem um desempenho melhor que o seu advers\u00e1rio, para somente ent\u00e3o iniciar o procedimento de ultrapassagem.<br \/>\nSabemos que uma das t\u00e9cnicas de ultrapassagem \u00e9 colocar o advers\u00e1rio sob press\u00e3o, mas essa press\u00e3o n\u00e3o pode ser exercida de forma que se tire o direito de disputa do mesmo, n\u00e3o se pode dar toques seguidos ou mesmo ao longo das voltas. N\u00e3o se pode meter o bico do carro para tentar empurrar o advers\u00e1rio, usando a parte interna da pista al\u00e9m da zebra.<br \/>\nTodas essas a\u00e7\u00f5es n\u00e3o s\u00e3o uma forma de press\u00e3o, portanto respeite sempre os espa\u00e7os, evite pequenos toques, ande perto mas n\u00e3o toque, antecipe as freadas, espere o erro do seu advers\u00e1rio, mas se este n\u00e3o comete-lo, aceite pois o m\u00e9rito \u00e9 dele.<br \/>\nN\u00e3o mude sua trajet\u00f3ria na inten\u00e7\u00e3o de garantir sua ultrapassagem ou ap\u00f3s obter \u00eaxito chegar \u00e0 pr\u00f3xima curva freando antecipadamente, para segurar seu advers\u00e1rio. Essas condutas caracterizam infra\u00e7\u00e3o de dire\u00e7\u00e3o perigosa. Da mesma forma que seu advers\u00e1rio defendeu sua posi\u00e7\u00e3o, voc\u00ea ter\u00e1 que faz\u00ea-lo na pr\u00f3xima curva.<br \/>\nEm momentos de ultrapassagem tome cuidado, pois caso venha a dar um leve toque que desequilibre seu advers\u00e1rio e com isso ganhe sua posi\u00e7\u00e3o voc\u00ea estar\u00e1 sujeito a penalidade.<\/li>\n<li>Todos os pilotos dever\u00e3o praticar o jogo limpo (Fairplay) e respeitar os demais que est\u00e3o participando da corrida.<\/li>\n<li>Todos os arquivos necess\u00e1rios e de distribui\u00e7\u00e3o gratuita utilizados nas corridas est\u00e3o dispon\u00edveis para download no Steam.<\/li>\n<\/ol>\n<h4 style=\"text-align: center;\"><strong>J<em>USTIFICATIVA DE AUS\u00caNCIA DOS PILOTOS:<\/em><\/strong><\/h4>\n<p>Os participantes ter\u00e3o at\u00e9 24 horas antes do evento para avisar a organiza\u00e7\u00e3o, via WhatsApp, a sua aus\u00eancia, caso contr\u00e1rio, estar\u00e1 automaticamente cedendo seu lugar nas pr\u00f3ximas etapas aos interessados da lista de espera.<\/p>\n<p>Na justificativa, o piloto deve deixar claro o motivo de sua aus\u00eancia, informando tamb\u00e9m se pretende continuar participando do campeonato.<\/p>\n<p>Em caso de aus\u00eancia o Piloto inscrito no campeonato, este poder\u00e1 indicar um Piloto substituto.<br \/>\nO Piloto substituto dever\u00e1 usar o carro do Piloto inscrito, os pontos marcados pelo Piloto substituto ser\u00e3o computados somente a ele, para a equipe os pontos contam normalmente.<br \/>\nSer\u00e1 permitido at\u00e9 duas substitui\u00e7\u00f5es de Piloto, n\u00e3o sendo permitido substitui\u00e7\u00e3o na \u00faltima etapa do campeonato.<\/p>\n<p>A Liga VPG tem como meta realizar competi\u00e7\u00f5es de automobilismo virtual em alto n\u00edvel; com muito divertimento, organiza\u00e7\u00e3o, e a cultura da competi\u00e7\u00e3o; com Lealdade e \u00c9tica. Apresentamos a seguir os destaques do Regulamento de Competi\u00e7\u00f5es da Temporada:<\/p>\n<h4 style=\"text-align: center;\"><strong>DESTAQUES:<\/strong><\/h4>\n<ol>\n<li>A) Todos os incidentes ter\u00e3o que ser reportados <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfTyrR1k70Z5gPoxJHAdZEIE9PLPMNOU_QFAQV0dEae8gRzDw\/viewform\">via formul\u00e1rio de protestos<\/a>, a liga n\u00e3o mais far\u00e1 a an\u00e1lise autom\u00e1tica da primeira volta.<br \/>\nB) Acidentes na primeira volta ter\u00e3o penaliza\u00e7\u00e3o com peso dobrado;<br \/>\nC) O Diretor de Prova ativo atua on-line, e \u00e9 tamb\u00e9m o Analista dos Protestos e Defesas Pr\u00e9vias;<br \/>\nD) O Diretor de Prova p\u00f3s-corrida \u00e9 tamb\u00e9m Analista dos Protestos e Defesas Pr\u00e9vias da categoria;<br \/>\nE) Em casos de discord\u00e2ncia para uma penalidade (n\u00e3o a sua escolha), h\u00e1 a possibilidade de Recorrer atrav\u00e9s:<\/li>\n<\/ol>\n<ul>\n<li>Envio de Recurso\u00a0 via <a href=\"http:\/\/www.ligavpg.com\/blog\/protesto-ou-defesa-previa\/\">Formul\u00e1rio de Protesto, Defesa Pr\u00e9via ou Recurso<\/a>.<\/li>\n<li>Enviar at\u00e9 24h ap\u00f3s a publica\u00e7\u00e3o das penalidades da etapa;<\/li>\n<\/ul>\n<ol>\n<li>F) Todos os pilotos devem entrar no <a href=\"https:\/\/discord.gg\/GZqGMGT\">Discord da VPG<\/a> a partir dos Treinos Livres no dia da etapa;<\/li>\n<\/ol>\n<ul>\n<li>[21:40] \u2013 Briefing com o Diretor de Prova e todos os pilotos, com presen\u00e7a obrigat\u00f3ria e ativa de todos;<\/li>\n<\/ul>\n<p><span style=\"color: #ff6600;\"><strong>Obs.:<\/strong> As instru\u00e7\u00f5es do Diretor de Prova no Briefing ser\u00e3o espec\u00edficas para aquela Prova; e nunca modificando o Regulamento para o futuro.<\/span><\/p>\n<ul>\n<li>[21:50] \u2013 Qualifica\u00e7\u00e3o de 5 a 10 minutos (espec\u00edficos das categorias), com setup livre;<\/li>\n<li>[21:55 \u2013 22:00] \u2013 Warm Up de 2 a 5 minutos, com setup de corrida;<\/li>\n<\/ul>\n<p><span style=\"color: #ff6600;\">Obs.: Contamos com o recurso de REJOIN, os pilotos que ca\u00edrem durante uma sess\u00e3o conseguir\u00e3o retornar ao servidor;<\/span><\/p>\n<ul>\n<li>[22:00 \u2013 22:05] \u2013 Corrida (os tempos e formatos s\u00e3o diversos de acordo com a categoria)<\/li>\n<\/ul>\n<ol>\n<li>G) S\u00f3 marcar\u00e3o pontos regulamentares na etapa os pilotos que completarem no m\u00ednimo 2\/3 da prova;<br \/>\n: Em espec\u00edfico para o simulador Automobilista 2, esta regra de 2\/3 n\u00e3o pode ser aplicada. Atualmente, o simulador n\u00e3o gera log de registro da corrida. O resultado v\u00e1lido, e que ser\u00e1 levado em considera\u00e7\u00e3o, \u00e9 aquele mostrado no painel ao final da corrida.<\/li>\n<li>H) Caso ocorra algum problema t\u00e9cnico com o servidor e este venha cair durante uma corrida, seguiremos esta ordem:<\/li>\n<\/ol>\n<ul>\n<li>Se acontecer at\u00e9 1\/3 de corrida, esta ser\u00e1 reiniciada;<\/li>\n<li>Se acontecer entre os 1\/3 e 2\/3, valer\u00e3o apenas metade dos pontos;<\/li>\n<\/ul>\n<ol>\n<li>I) A liga utiliza o sistema de descarte autom\u00e1tico do pior resultado(coloca\u00e7\u00e3o) em uma etapa, ou de duas baterias, dependendo do formato do campeonato. Exclui-se do descarte:<\/li>\n<\/ol>\n<ul>\n<li>Etapas em que o piloto foi desclassificado (DQ);<\/li>\n<li>\u00daltima etapa do campeonato.<\/li>\n<\/ul>\n<ol>\n<li>J) A pr\u00e1tica do Fairplay ou Autopuni\u00e7\u00e3o(pass-through) ser\u00e3o avaliadas pela Dire\u00e7\u00e3o de Prova; render\u00e3o um desconto de &gt;metade mais um&lt; segundos de uma penaliza\u00e7\u00e3o, ou a julgamento da an\u00e1lise, at\u00e9 a supress\u00e3o da mesma. Basta avisar da pr\u00e1tica numa DEFESA PR\u00c9VIA.<\/li>\n<\/ol>\n<ul>\n<li>O \u201cpass-through\u201d volunt\u00e1rio, uma passagem pelos boxes em baixa velocidade, o piloto que o fizer por conta pr\u00f3pria ap\u00f3s se julgar culpado por algum incidente, deve informar pelo Formul\u00e1rio de Defesa Pr\u00e9via do fato no dia seguinte \u00e0 prova, como assun\u00e7\u00e3o de culpa e poss\u00edvel atenuante na an\u00e1lise;<\/li>\n<\/ul>\n<ol>\n<li>K) O piloto que atalhar ou alargar ter\u00e1 sua penalidade eliminada, se \u201ctirar o p\u00e9\u201d por tempo equivalente, de imediato;<br \/>\nL) As penalidades repetidas ter\u00e3o peso x1,5 (cumulativo) nas etapas seguintes da Temporada; sem preju\u00edzo de mais agravantes nas penalidades em sua nova repeti\u00e7\u00e3o, podendo chegar ao convite para n\u00e3o mais participar da Liga;<br \/>\nM) No simulador Rfactor 2, as penaliza\u00e7\u00f5es s\u00e3o por tempo acrescido ao final da etapa. Caso o piloto n\u00e3o complete a prova ou termine dentro das voltas v\u00e1lidas (2\/3), a penaliza\u00e7\u00e3o neste caso ser\u00e1 cumprida na etapa seguinte a participa\u00e7\u00e3o do piloto. Na falta de oportunidades para o cumprimento da mesma, a penaliza\u00e7\u00e3o ser\u00e1 convertida em pontos.<br \/>\nN) No simulador Automobilista 2, as penaliza\u00e7\u00f5es s\u00e3o por pontos descontados ao final da etapa.<br \/>\nO) Quanto ao FPS e PING necess\u00e1rios:<\/li>\n<\/ol>\n<ul>\n<li>O FPS ter\u00e1 de ser sempre maior que 40, com risco de ser \u201ckickado\u201d pelo Diretor de Prova<\/li>\n<li>O Ping ter\u00e1 que ser sempre menor que 400, com risco de ser \u201ckickado\u201d pelo Diretor de Prova<\/li>\n<\/ul>\n<ol>\n<li>P) A Liga promover\u00e1 benef\u00edcios e\/ou sorteios para os mais ass\u00edduos e sem penalidades grav\u00edssimas (inclusive DQ), assim como premiar\u00e1 os Campe\u00f5es das Categorias com um Trof\u00e9u da Liga VPG.<br \/>\nQ) As penalidades da \u00faltima etapa, se entendidas como anti-jogo, atingir\u00e3o todos os pilotos de uma mesma equipe;<br \/>\nR) N\u00e3o ser\u00e3o permitidas novas inscri\u00e7\u00f5es e participa\u00e7\u00e3o de novos pilotos numa categoria, na \u00faltima etapa de uma Temporada;<br \/>\nS) Os empurr\u00f5es nas retas n\u00e3o ser\u00e3o permitidos; nem entre colegas de equipe.<br \/>\nT) O Hotlaps ser\u00e1 o modo de avaliar os treinos dos pilotos, avaliar a quantidade de voltas <u>completas<\/u> (Clean), caso seja exigido pelo regulamento espec\u00edfico da categoria.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: center;\"><strong>RESUMO DAS REGRAS PARA AN\u00c1LISE E PENALIZA\u00c7\u00d5ES<\/strong><\/h4>\n<ul>\n<li>As penalidades s\u00e3o por tempo acrescentado, com agravantes ou atenuantes, a crit\u00e9rio da administra\u00e7\u00e3o e do Diretor de Prova Analista;<\/li>\n<li>Os acidentes ter\u00e3o avalia\u00e7\u00e3o positiva no uso de FAIRPLAY, AUTOPUNI\u00c7\u00c3O, DEFESA PR\u00c9VIA;<\/li>\n<li>As penalidades ser\u00e3o pass\u00edveis de recursos, mas as decis\u00f5es ser\u00e3o mantidas enquanto perdurar a rean\u00e1lise;<br \/>\n<span style=\"color: #ff6600;\"><strong>Obs.:<\/strong> Para ser poss\u00edvel fazer um RECURSO, deve ser usado o modelo pr\u00f3prio, na janela de tempo regulamentar, e seu preenchimento deve informar totalmente a descri\u00e7\u00e3o do acidente sob pena de n\u00e3o permitir a an\u00e1lise do Recurso, e perda da sua fun\u00e7\u00e3o para esclarecer o DP Analista.<\/span><\/li>\n<li>A falta de participa\u00e7\u00e3o obrigat\u00f3ria no briefing n\u00e3o \u00e9 atenuante para os erros, e pode impedir a participa\u00e7\u00e3o na prova;<\/li>\n<li>As equipes podem ter at\u00e9 4 pilotos, onde os 3 melhores resultados ser\u00e3o computados no SLS;<\/li>\n<li><span style=\"color: #008000;\">Incidentes flagrados por parte da transmiss\u00e3o ao vivo podem ser inclu\u00eddos na analise independente de protesto.<\/span><\/li>\n<li>As penalidades durante a Qualifica\u00e7\u00e3o ser\u00e3o aplicadas conforme as regras e, caso algum piloto informe imediatamente que cometeu alguma infra\u00e7\u00e3o n\u00e3o registrada, somente aquela volta ser\u00e1 retirada, sem penalidade.<\/li>\n<li>As penalidades sofrer\u00e3o peso 1,5 cumulativo para os pilotos reincidentes em etapas seguintes;<br \/>\n<span style=\"color: #ff6600;\"><strong>Obs.:<\/strong> Se a reincid\u00eancia for na etapa seguinte, e pela mesma raz\u00e3o, o piloto largar\u00e1 dos Boxes em qualquer etapa seguinte ap\u00f3s a penalidade;<\/span><\/li>\n<li>As penalidades do dia da(s) \u00faltima(s) etapa(s) atingir\u00e3o todos os pilotos de uma equipe na pista naquele momento. Caso este seja interpretado como conduta antidesportiva a postulantes ao t\u00edtulo.<\/li>\n<\/ul>\n<h4 style=\"text-align: center;\"><strong>PENALIZA\u00c7\u00d5ES EDUCATIVAS:<\/strong><\/h4>\n<h5><span style=\"color: #ff9900;\"><strong>PENALIZA\u00c7\u00c3O LEVE [10 segundos por ocorr\u00eancia ou 5 posi\u00e7\u00f5es no grid da prova seguinte do piloto na Liga VPG]<\/strong><\/span><\/h5>\n<p><span style=\"color: #00ccff;\">3.6. Usar chat em Modo Espectador na classifica\u00e7\u00e3o e\/ou corrida<\/span><br \/>\n<span style=\"color: #00ccff;\">9.1.4. Uso de chat durante a classifica\u00e7\u00e3o e\/ou corrida<\/span><br \/>\n<span style=\"color: #00ccff;\">9.2.8.1. Retornar \u00e0 pista atrapalhando outro, sem preju\u00edzo<\/span><br \/>\n<span style=\"color: #00ccff;\">9.2.10. N\u00e3o respeitar a linha de sa\u00edda dos boxes<\/span><br \/>\n<span style=\"color: #00ccff;\">9.2.14. Piscar farol durante a classifica\u00e7\u00e3o e\/ou corrida \u2013 salvo o 1\u00ba. colocado na chegada<\/span><br \/>\n<span style=\"color: #00ccff;\">9.3. Atalhar ou alargar trajet\u00f3ria, fora das linhas laterais*<\/span><\/p>\n<ul>\n<li><span style=\"color: #00ccff;\">Obs.1: Anotadas mais que 10 faltas no item 9.3 causar\u00e3o a DQ do piloto na prova;<\/span><\/li>\n<li><span style=\"color: #00ccff;\">Obs.2: Em disputa de posi\u00e7\u00e3o, o piloto que atalhar ou alargar n\u00e3o poder\u00e1 defender posi\u00e7\u00e3o ou fazer ultrapassagem at\u00e9 a pr\u00f3xima reta.<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #00ccff;\">9.7. Ultrapassagem em bandeira amarela.<\/span><br \/>\n<span style=\"color: #00ccff;\">9.8. Ultrapassagem dentro dos boxes.<\/span><\/p>\n<h5><span style=\"color: #ff9900;\"><strong>PENALIZA\u00c7\u00c3O M\u00c9DIA [15 segundos por ocorr\u00eancia ou 10 posi\u00e7\u00f5es no grid da prova seguinte do piloto na Liga]<\/strong><\/span><\/h5>\n<p><span style=\"color: #ffcc00;\">9.2.1. Dire\u00e7\u00e3o perigosa, com preju\u00edzo para o oponente<\/span><br \/>\n<span style=\"color: #ffcc00;\">9.2.8. Retornar \u00e0 pista atrapalhando outro, desequilibrando-o<\/span><br \/>\n<span style=\"color: #ffcc00;\">9.2.9. Sair do boxe sem dar prioridade a quem vem na pista<\/span><br \/>\n<span style=\"color: #ffcc00;\">9.2.12. Bater em outro advers\u00e1rio por tr\u00e1s<\/span><br \/>\n<span style=\"color: #ffcc00;\">9.2.13. Mudar de dire\u00e7\u00e3o mais de uma vez por reta, \u00e0 frente de colega, de forma perigosa<\/span><br \/>\n<span style=\"color: #ffcc00;\">9.2.13.1. Mudar de dire\u00e7\u00e3o estando ao lado de oponente causando acidente ou perda de posi\u00e7\u00e3o<\/span><br \/>\n<span style=\"color: #ffcc00;\">9.2.13.2. N\u00e3o deixar espa\u00e7o para o colega na pista(empurrar), em disputa lateral, causando acidente ou perda de posi\u00e7\u00e3o.<\/span><br \/>\n<span style=\"color: #ffcc00;\">9.2.13.3. Dividir curva espalhando em oponente causando acidente ou perda de posi\u00e7\u00e3o<\/span><\/p>\n<h5><span style=\"color: #ff9900;\"><strong>PENALIZA\u00c7\u00c3O GRAVE [20 segundos por ocorr\u00eancia, ou sem Qualy na prova seguinte do piloto na Liga VP]<\/strong><\/span><\/h5>\n<p><span style=\"color: #ff9900;\">9.2.8.2. Retornar \u00e0 pista causando acidente de outro, com perda de posi\u00e7\u00e3o ou avarias tempor\u00e1rias<\/span><br \/>\n<span style=\"color: #ff9900;\">9.2.8.3. N\u00e3o deixar espa\u00e7o para o colega na pista, em disputa, causando acidente com perda de posi\u00e7\u00e3o e\/ou avarias<\/span><\/p>\n<ul>\n<li><span style=\"color: #ff9900;\">Obs.: Inclui-se nesta regra, a ultrapassagem indevida em entrada de curva. No momento anterior a frenagem e\/ou tomada de curva, o piloto que tentar uma ultrapassagem precisar\u00e1 estar no m\u00ednimo com o seu seu eixo dianteiro alinhado com o eixo traseiro do piloto a ser ultrapassado.<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #ff9900;\">9.2.8.4. Dividir curva espalhando em oponente causando acidente, com perda de posi\u00e7\u00e3o ou avarias tempor\u00e1rias<\/span><\/p>\n<ul>\n<li><span style=\"color: #ff9900;\">Obs.: Mesma observa\u00e7\u00e3o do item 9.2.8.3.<\/span><\/li>\n<\/ul>\n<h5><span style=\"color: #ff9900;\"><strong>PENALIZA\u00c7\u00c3O GRAV\u00cdSSIMA [Perde uma volta ou na pr\u00f3xima etapa Largar\u00e1 dos boxes ou pagar\u00e1 um <em>Stop and Go<\/em>\u00a0na primeira volta]<\/strong><\/span><\/h5>\n<p><span style=\"color: #cc99ff;\">9.2.7. Andar no sentido contr\u00e1rio da pista<\/span><br \/>\n<span style=\"color: #cc99ff;\">9.2.1.4. Conduta antidesportiva, a crit\u00e9rio do Diretor de Prova e da Admin<\/span><br \/>\n<span style=\"color: #cc99ff;\">9.6. Discutir incidentes no WhatsApp, Redes Sociais, Briefing ou no Chat do jogo.<\/span><br \/>\n<span style=\"color: #cc99ff;\">9.5.1. Sair dos boxes com sinal vermelho<\/span><br \/>\n<span style=\"color: #cc99ff;\">9.1.5. N\u00e3o seguir determina\u00e7\u00f5es da Dire\u00e7\u00e3o de Prova imediatamente<\/span><br \/>\n<span style=\"color: #cc99ff;\">9.2.8.5. Retornar \u00e0 pista causando acidente sem possibilidade de retorno do outro<\/span><br \/>\n<span style=\"color: #cc99ff;\">9.2.8.6. N\u00e3o deixar espa\u00e7o para o colega na pista, em disputa, causando acidente sem possibilidade de retorno do outro<\/span><br \/>\n<span style=\"color: #cc99ff;\">9.2.8.7. Dividir curva espalhando em oponente causando acidente sem possibilidade de retorno do outro<\/span><\/p>\n<ul>\n<li><span style=\"color: #cc99ff;\">Obs.: Mesma observa\u00e7\u00e3o do item 9.2.8.3.<\/span><\/li>\n<\/ul>\n<h4 style=\"text-align: center;\"><strong>CASOS ESPECIAIS:<\/strong><\/h4>\n<p>9.4.2a. \u2013 N\u00e3o cumprir no m\u00ednimo 20 voltas limpas completadas no servidor e aferidas pelo Hotlaps antes do Qualy (De acordo com regra espec\u00edfica da categoria) &gt; Impedido de participar do Qualy (larga no fim do grid);<br \/>\n9.4.2c. Faltas Disciplinares, a crit\u00e9rio do DP ou da Admin: DQ + SEM Qualy na etapa seguinte<br \/>\n9.4.2d \u2013 Falta Grave ou DQ: Perde o direito de participar de sorteios ou promo\u00e7\u00f5es<br \/>\n9.4.2e \u2013 N\u00e3o ser\u00e1 aceito que o carro emita fuma\u00e7a no Qualy (radiador 1), em respeito aos colegas e \u00e0 transmiss\u00e3o \u2013 penalidade largar no fim do Grid.<br \/>\n9.4.2f \u2013 A presen\u00e7a no Briefing \u00e9 obrigat\u00f3ria, na falta, o piloto automaticamente largar\u00e1 no fim do Grid. Em casos especiais, a crit\u00e9rio do diretor de prova, o piloto pode at\u00e9 ser impedido de participar da prova;<\/p>\n<h4 style=\"text-align: center;\"><strong>SISTEMA DE BONIFICA\u00c7\u00c3O:<\/strong><\/h4>\n<ol>\n<li>A) Pole position = 1 ponto<br \/>\nB) Volta mais r\u00e1pida = 1 ponto<br \/>\nC) Bonifica\u00e7\u00e3o por terminar uma prova = 3 pontos para DTM e GT3, e 5 para Endurance.<\/li>\n<\/ol>\n<h4 style=\"text-align: center;\"><strong>AUTOPUNI\u00c7\u00c3O, DEFESA PR\u00c9VIA, PROTESTO, RECURSO e FAIRPLAY:<\/strong><\/h4>\n<h5>Autopuni\u00e7\u00e3o:<\/h5>\n<p>O piloto ter\u00e1 redu\u00e7\u00e3o ou elimina\u00e7\u00e3o de puni\u00e7\u00e3o, se decidir por fazer um PASS-THROUGH pelo Box, registrando assim sua assun\u00e7\u00e3o de culpa num incidente.<\/p>\n<h5>Defesa Pr\u00e9via:<\/h5>\n<p>O piloto deve mandar o Formul\u00e1rio preenchido correta e completamente para o Diretor de Prova no dia seguinte ao da etapa, fazendo sua an\u00e1lise da participa\u00e7\u00e3o num incidente; na falta deste e havendo protesto de colega que fique confirmado na an\u00e1lise, as puni\u00e7\u00f5es ser\u00e3o rigorosas, e o piloto perde o direito de recorrer de uma penalidade.<br \/>\nOBS: Na aus\u00eancia de protesto a defesa pr\u00e9via ser\u00e1 desconsiderada.<\/p>\n<h4 style=\"text-align: center;\"><strong>Protesto:<\/strong><\/h4>\n<p>O piloto que se julgar prejudicado por um colega, deve enviar seu Formul\u00e1rio de protesto somente no segundo dia ap\u00f3s a etapa. Exclusos destes prazos, os fins de semana e feriados nacionais.<br \/>\nObs.1: O replay pr\u00f3prio do piloto pode ser usado como base para o Protesto; o Replay oficial ser\u00e1 utilizado na eventual revis\u00e3o do DP.<br \/>\nObs.2: Na Prova, o piloto s\u00f3 pode protestar no per\u00edodo em que estiver em disputa de posi\u00e7\u00e3o.<br \/>\nObs.3: Na Qualifica\u00e7\u00e3o, todos pilotos podem protestar todo o tempo, pois todos est\u00e3o em disputa direta.<\/p>\n<h4 style=\"text-align: center;\"><strong>Recursos:<\/strong><\/h4>\n<p>N\u00e3o concordando com uma penalidade, o piloto poder\u00e1 enviar recurso, em at\u00e9 24h da publica\u00e7\u00e3o, explicando suas raz\u00f5es. Ao segundo julgamento n\u00e3o caber\u00e1 recurso.<\/p>\n<p><strong>Normas para envio de Defesas Pr\u00e9vias e Protestos:<\/strong><\/p>\n<p>ATEN\u00c7\u00c3O: A Liga fornece modelo pr\u00f3prio de formul\u00e1rio para que n\u00e3o faltem os detalhes abaixo nas remessas, sem o que poder\u00e3o n\u00e3o ser\u00e3o considerados.<br \/>\nLink do Formul\u00e1rio:<a href=\"http:\/\/www.ligavpg.com\/blog\/protesto-ou-defesa-previa\/\"><strong>http:\/\/www.ligavpg.com\/blog\/protesto-ou-defesa-previa\/<\/strong><\/a><br \/>\nA) O piloto deve informar no Formul\u00e1rio de Defesa Pr\u00e9via ou Protesto, a \u201cEtapa\u201d e a \u201cCategoria\u201d: Ex: \u201cProtesto \u2013 1\u00aa etapa \u2013 PRO\u201d<br \/>\nB) O piloto deve informar no \u201cCONTE\u00daDO\u201d do formul\u00e1rio o n\u00famero da volta, o tempo na volta, e os pilotos envolvidos no incidente; caso n\u00e3o o fa\u00e7a corretamente e especificamente nesta ordem a penaliza\u00e7\u00e3o pleiteada poder\u00e1 ser desconsiderada, se houver excesso de casos.<br \/>\nC) O conte\u00fado da mensagem deve fazer as explica\u00e7\u00f5es necess\u00e1rias para que o Diretor de Prova e o Analista tenha seu trabalho facilitado, diminuindo assim a possibilidade de erro,<br \/>\nD) As decis\u00f5es do Analista ser\u00e3o irrecorr\u00edveis, salvo o disposto no item acima \u201cRecursos\u201d<br \/>\nE) As an\u00e1lises s\u00e3o feitas a partir do REPLAY publicado.<\/p>\n<h4 style=\"text-align: center;\"><strong>Explica\u00e7\u00f5es sobre o Fairplay:<\/strong><\/h4>\n<p>Fairplay significa jogo limpo. \u00c9 uma quest\u00e3o de moral e \u00e9tica no esporte, que serve de exemplo para a vida. \u00c9 exemplo de uma conduta leal; dando exemplo aos que assistem a prova.<\/p>\n<p><strong>Fairplay x Penaliza\u00e7\u00e3o<\/strong><\/p>\n<p>Dois pilotos em disputa, o segundo acerta o primeiro e o tira da briga, o primeiro espera o segundo voltar e devolve a posi\u00e7\u00e3o, imediatamente e at\u00e9 o final da reta seguinte;<br \/>\nImplica\u00e7\u00f5es:<br \/>\nO segundo colocado, j\u00e1 que teve uma conduta digna de Fairplay, j\u00e1 n\u00e3o seria penalizado se n\u00e3o houvesse preju\u00edzo para o colega (seja de rendimento, seja de perdas adicionais de posi\u00e7\u00f5es) com o acidente, mas havendo estas perdas, ainda restar\u00e3o preju\u00edzos a compensar.<br \/>\nEnt\u00e3o, o segundo piloto ainda ser\u00e1 penalizado, mas poder\u00e1 ter sua penaliza\u00e7\u00e3o reduzida em 50%.<br \/>\nO Fairplay neste caso serviu para demonstrar para o primeiro piloto e a todos, que o mesmo assume a culpa do ocorrido, al\u00e9m de mostrar a lealdade e \u00e9tica que este possui, se esfor\u00e7ando para praticar o jogo limpo.<\/p>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: center;\"><strong>BANDEIRAS QUE PODEM SURGIR DURANTE UMA CORRIDA<\/strong><\/h4>\n<div id=\"attachment_16319\" style=\"width: 360px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-16319\" class=\"wp-image-16319\" src=\"http:\/\/www.ligavpg.com\/blog\/wp-content\/uploads\/Bandeiras-infografico-69x300.jpg\" alt=\"Bandeiras de corrida\" width=\"350\" height=\"1532\" srcset=\"http:\/\/www.ligavpg.com\/blog\/wp-content\/uploads\/\/Bandeiras-infografico-234x1024.jpg 234w, http:\/\/www.ligavpg.com\/blog\/wp-content\/uploads\/\/Bandeiras-infografico-768x3360.jpg 768w, http:\/\/www.ligavpg.com\/blog\/wp-content\/uploads\/\/Bandeiras-infografico-351x1536.jpg 351w, http:\/\/www.ligavpg.com\/blog\/wp-content\/uploads\/\/Bandeiras-infografico-468x2048.jpg 468w, http:\/\/www.ligavpg.com\/blog\/wp-content\/uploads\/\/Bandeiras-infografico-scaled.jpg 585w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><p id=\"caption-attachment-16319\" class=\"wp-caption-text\">Fonte: esportelandia<\/p><\/div>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: center;\"><strong>REGRAS DE CONDUTA nos grupos de WhatsApp<\/strong><\/h4>\n<ol>\n<li>As inscri\u00e7\u00f5es s\u00e3o feitas exclusivamente online e aprovadas t\u00e3o unicamente por an\u00e1lise da administra\u00e7\u00e3o;<\/li>\n<li>Todo usu\u00e1rio tem o direito de postar sobre sua d\u00favida em rela\u00e7\u00e3o ao nosso prop\u00f3sito inicial, que \u00e9 trocar informa\u00e7\u00f5es sobre jogos simuladores e eventualmente hardware e software envolvidos.<\/li>\n<li>\u00c9 proibida a indica\u00e7\u00e3o de sites de conte\u00fado adulto, bem como o conte\u00fado impr\u00f3prio para menores tamb\u00e9m tem sua divulga\u00e7\u00e3o proibida. Os usu\u00e1rios que ferirem esse princ\u00edpio ser\u00e3o banidos temporariamente ou de forma permanente;<\/li>\n<li>\u00c9 proibida a divulga\u00e7\u00e3o de informa\u00e7\u00f5es que incentivem crimes fiscais, entre outros crimes previstos em lei, onde se inclui a sonega\u00e7\u00e3o de impostos, a cal\u00fania, a difama\u00e7\u00e3o, e a divulga\u00e7\u00e3o de falsas alega\u00e7\u00f5es;<\/li>\n<li>A conviv\u00eancia de qualquer membro est\u00e1 ligada ao respeito m\u00fatuo de cada um. Ofensas ou brigas n\u00e3o s\u00e3o permitidas e os usu\u00e1rios envolvidos ser\u00e3o banidos;<\/li>\n<li>\u00c9 proibido a postagem referentes a pol\u00edtica, nacional ou internacional;<\/li>\n<li>Postagens n\u00e3o permitidas ser\u00e3o deletadas pelos administradores, e o respons\u00e1vel pela postagem poder\u00e1 ser exclu\u00eddo do grupo de forma tempor\u00e1ria ou permanente;<\/li>\n<li>O uso de linguajar inadequado ou mensagens com teor provocativo incitando revolta ou tumulto tamb\u00e9m n\u00e3o s\u00e3o permitidos, tais mensagens ser\u00e3o exclu\u00eddas e seus respectivos autores expulsos;<\/li>\n<li>A conviv\u00eancia pac\u00edfica entre os membros dos grupos \u00e9 fundamental. Nossa miss\u00e3o \u00e9 crescer dia a dia, acrescentando informa\u00e7\u00f5es relevantes ao conhecimento de tecnologia, compartilhando experi\u00eancias entre a comunidade de interessados em conviver dentro desta finalidade. Usu\u00e1rios que n\u00e3o compreendem esse esp\u00edrito e se comportarem de forma prejudicial ao bom andamento ser\u00e3o expulsos.<\/li>\n<\/ol>\n<h4><\/h4>\n<h4 style=\"text-align: center;\"><strong><em>Carteira de Pontos do Piloto<\/em><\/strong><\/h4>\n<p>Cada infra\u00e7\u00e3o cometida por um Piloto ter\u00e1 uma pontua\u00e7\u00e3o acrescida em sua carteira, esses pontos se somam durante um campeonato, conforme a pontua\u00e7\u00e3o atingida as puni\u00e7\u00f5es ser\u00e3o aplicadas.<\/p>\n<p><strong>O Piloto que atingir a marca de 15 pontos em um campeonato, ser\u00e1 automaticamente exclu\u00eddo da corrida seguinte em que atingiu a pontua\u00e7\u00e3o m\u00e1xima.<\/strong><\/p>\n<p>Os pontos que o Piloto tiver em sua carteira ser\u00e3o zerados ao termino de cada campeonato.<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<h4 style=\"text-align: center;\"><strong><em>Penaliza\u00e7\u00e3o em pontos por puni\u00e7\u00e3o:<\/em><\/strong><\/h4>\n<h5 style=\"text-align: center;\"><em><span style=\"color: #ff9900;\">Advert\u00eancia: 1 ponto<\/span><\/em><br \/>\n<em><span style=\"color: #ff9900;\">Penaliza\u00e7\u00e3o leve: 2 pontos<\/span><\/em><br \/>\n<em><span style=\"color: #ff9900;\">Penaliza\u00e7\u00e3o m\u00e9dia: 3 pontos<\/span><\/em><br \/>\n<em><span style=\"color: #ff9900;\">Penaliza\u00e7\u00e3o grave: 5 pontos<\/span><\/em><\/h5>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; REGULAMENTO DE COMPETI\u00c7\u00d5ES Regras, Penaliza\u00e7\u00f5es e Recursos Data da atualiza\u00e7\u00e3o: 20\/01\/2025 \u00a0 REGULAMENTO GERAL DA LIGA VPG REGRAS DE CONDUTA Este regulamento visa padronizar os procedimentos e condutas de todos antes de entrar no servidor e durante todas as sess\u00f5es das corridas. Com ele, voc\u00ea saber\u00e1 antecipadamente qual a conduta correta que voc\u00ea dever\u00e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12297,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"open","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-88","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/ligavpg.com\/blog\/wp-json\/wp\/v2\/pages\/88","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligavpg.com\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ligavpg.com\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ligavpg.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ligavpg.com\/blog\/wp-json\/wp\/v2\/comments?post=88"}],"version-history":[{"count":221,"href":"https:\/\/ligavpg.com\/blog\/wp-json\/wp\/v2\/pages\/88\/revisions"}],"predecessor-version":[{"id":17167,"href":"https:\/\/ligavpg.com\/blog\/wp-json\/wp\/v2\/pages\/88\/revisions\/17167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligavpg.com\/blog\/wp-json\/wp\/v2\/media\/12297"}],"wp:attachment":[{"href":"https:\/\/ligavpg.com\/blog\/wp-json\/wp\/v2\/media?parent=88"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}